{"id":59426,"date":"2009-05-17T11:16:02","date_gmt":"2009-05-17T09:16:02","guid":{"rendered":"https:\/\/www.claret.org\/encuentro-obispos-y-misioneros-voluntarios\/"},"modified":"2009-05-17T11:16:02","modified_gmt":"2009-05-17T09:16:02","slug":"encuentro-obispos-y-misioneros-voluntarios","status":"publish","type":"post","link":"https:\/\/www.claret.org\/es\/encuentro-obispos-y-misioneros-voluntarios\/","title":{"rendered":"Encuentro Obispos y Misioneros voluntarios"},"content":{"rendered":"<p><b>Sud\u00e1n<\/b>. Los padres claretianos Rosendo Urrabazo (Vicario General) y Joseph Callixtus (voluntario en Sud\u00e1n) asistieron a un encuentro celebrado en Juba los d\u00edas 29 y 30 de abril entre los Obispos de Sud\u00e1n y los miembros de la Junta de \u00ab<b>Solidaridad para el sur de Sud\u00e1n<\/b>\u00ab, iniciativa de los Superiores y Superioras generales en Roma. Ochenta y ocho congregaciones religiosas colaboran con personal y con recursos para proporcionar educaci\u00f3n, salud y servicios pastorales a la poblaci\u00f3n del Sud\u00e1n meridional. En esta reuni\u00f3n, los obispos firmaron un \u201cMemorando de entendimiento\u201d con la Junta de Solidaridad para seguir desarrollando el proyecto.<\/p>\n<p>El P. Callixtus Joseph, natural de Sri Lanka, perteneciente a la Provincia claretiana de Alemania, es el Secretario administrativo del proyecto y de la vida en Juba; El P. Rosendo es representante del P. General y es Vicepresidente de la Junta.<\/p>\n<p>Actualmente, hay 19 misioneros de diversas congregaciones que participan en este proyecto y que trabajan en cuatro localidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sud\u00e1n. Los padres claretianos Rosendo Urrabazo (Vicario General) y Joseph Callixtus (voluntario en Sud\u00e1n) asistieron a un encuentro celebrado en Juba los d\u00edas 29 y 30 de abril entre los Obispos de Sud\u00e1n y los miembros de la Junta de \u00abSolidaridad para el sur de Sud\u00e1n\u00ab, iniciativa de los Superiores y Superioras generales en Roma. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[566,528,431,422,445],"tags":[],"class_list":["post-59426","post","type-post","status-publish","format-standard","hentry","category-cardenales-y-obispos","category-familia-claretiana","category-pastoral-de-la-salud","category-pastoral-educativa","category-solidaridad-y-mision"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdaBmi-fsu","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.claret.org\/es\/wp-json\/wp\/v2\/posts\/59426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claret.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.claret.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.claret.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claret.org\/es\/wp-json\/wp\/v2\/comments?post=59426"}],"version-history":[{"count":0,"href":"https:\/\/www.claret.org\/es\/wp-json\/wp\/v2\/posts\/59426\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.claret.org\/es\/wp-json\/wp\/v2\/media?parent=59426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.claret.org\/es\/wp-json\/wp\/v2\/categories?post=59426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.claret.org\/es\/wp-json\/wp\/v2\/tags?post=59426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}