{"id":147900,"date":"2023-05-29T17:00:00","date_gmt":"2023-05-29T15:00:00","guid":{"rendered":"https:\/\/www.claret.org\/conversation-avec-le-pape-francois-dans-le-cadre-du-projet-etre-ensemble-a-la-residence-claret-granada\/"},"modified":"2023-05-30T09:04:16","modified_gmt":"2023-05-30T07:04:16","slug":"conversation-avec-le-pape-francois-dans-le-cadre-du-projet-etre-ensemble-a-la-residence-claret-granada","status":"publish","type":"post","link":"https:\/\/www.claret.org\/fr\/conversation-avec-le-pape-francois-dans-le-cadre-du-projet-etre-ensemble-a-la-residence-claret-granada\/","title":{"rendered":"Conversation avec le pape Fran\u00e7ois dans le cadre du projet \u00ab\u00a0\u00catre ensemble\u00a0\u00bb \u00e0 la r\u00e9sidence Claret Granada"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Granada, Espagne. Jeudi dernier, le 25 mai 2023, la r\u00e9sidence Claret Granada a \u00e9t\u00e9 le th\u00e9\u00e2tre d&rsquo;un \u00e9v\u00e9nement capital : les r\u00e9sidents ont eu la rare opportunit\u00e9 de s&rsquo;entretenir en direct avec Sa Saintet\u00e9 le pape Fran\u00e7ois dans le cadre du projet \u00ab\u00a0Being Together\u00a0\u00bb (\u00catre ensemble).  L&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 organis\u00e9 principalement par la Fondation Scholas, et l&rsquo;\u00e9change fascinant a \u00e9t\u00e9 diffus\u00e9 dans le monde entier avec le soutien de Telemundo.<\/p>\n\n<p>Au cours de l&rsquo;\u00e9mission en direct, l&rsquo;un des r\u00e9sidents a eu l&rsquo;occasion de demander \u00e0 Sa Saintet\u00e9 s&rsquo;il se souvenait d&rsquo;une conversation avec une personne \u00e2g\u00e9e au cours de sa jeunesse. Le pape a r\u00e9pondu par une exp\u00e9rience personnelle avec ses propres grands-parents et leur a expliqu\u00e9 combien il est important d&rsquo;apprendre de l&rsquo;exp\u00e9rience des personnes \u00e2g\u00e9es, et surtout de ce qu&rsquo;elles peuvent apporter \u00e0 la soci\u00e9t\u00e9.<\/p>\n\n<p>Ce fut une exp\u00e9rience unique, tr\u00e8s \u00e9mouvante et enrichissante.<\/p>\n\n<p>La vid\u00e9o compl\u00e8te peut \u00eatre visionn\u00e9e sur ce lien (l&rsquo;intervention des membres de la R\u00e9sidence Claret Granada, elle dure 51 minutes et 15 secondes) :<\/p>\n\n<p><a href=\"about:blank\">https:\/\/www.youtube.com\/watch?v=FTz5plfT9FM<\/a><\/p>\n\n<p><p>Source : Jos\u00e9 Luis Paredes Andr\u00e9s, Communication, Province de Fatima.<\/p><\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"147870\" src=\"https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_2.jpeg?resize=1024%2C575&#038;ssl=1\" alt=\"\" class=\"wp-image-147870\" title=\"\" srcset=\"https:\/\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_2-980x550.jpeg 980w, https:\/\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_2-480x269.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" data-id=\"147847\" src=\"https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_3.jpeg?resize=1024%2C472&#038;ssl=1\" alt=\"\" class=\"wp-image-147847\" title=\"\" srcset=\"https:\/\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_3-980x452.jpeg 980w, https:\/\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_3-480x221.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" data-id=\"147857\" src=\"https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_4.jpeg?resize=1024%2C472&#038;ssl=1\" alt=\"\" class=\"wp-image-147857\" title=\"\" srcset=\"https:\/\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_4-980x452.jpeg 980w, https:\/\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_4-480x221.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" data-id=\"147850\" src=\"https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_5.jpeg?resize=1024%2C472&#038;ssl=1\" alt=\"\" class=\"wp-image-147850\" title=\"\" srcset=\"https:\/\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_5-980x452.jpeg 980w, https:\/\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_5-480x221.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"472\" data-id=\"147865\" src=\"https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_6.jpeg?resize=1024%2C472&#038;ssl=1\" alt=\"\" class=\"wp-image-147865\" title=\"\" srcset=\"https:\/\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_6-980x452.jpeg 980w, https:\/\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_6-480x221.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"765\" height=\"1024\" data-id=\"147877\" src=\"https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_7.jpeg?resize=765%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-147877\" title=\"\"><\/figure>\n<\/figure>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\r\n<div class=\"epyt-video-wrapper\"><div  data-ep-a=\"fadeIn\"  id=\"_ytid_63900\"  width=\"1080\" height=\"608\"  data-origwidth=\"1080\" data-origheight=\"608\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/FTz5plfT9FM?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=1&#038;cc_lang_pref=&#038;iv_load_policy=3&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=1&#038;autohide=2&#038;hl=es_ES&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__ epyt-facade  epyt-is-override  no-lazyload\" data-epautoplay=\"1\" ><img data-recalc-dims=\"1\" decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\" alt=\"YouTube player\" src=\"https:\/\/i0.wp.com\/i.ytimg.com\/vi\/FTz5plfT9FM\/maxresdefault.jpg?w=1080&#038;ssl=1\" title=\"\"><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div><span itemprop=\"video\" itemscope itemtype=\"http:\/\/schema.org\/VideoObject\"><meta itemprop=\"embedUrl\" content=\"https:\/\/www.youtube.com\/embed\/FTz5plfT9FM\"><meta itemprop=\"name\" content=\"El papa Francisco se re\u00fane con j\u00f3venes latinos de Scholas | Telemundo\"><meta itemprop=\"description\" content=\"Video oficial de Telemundo. El papa Francisco habla con j\u00f3venes latinoamericanos en un foro moderado por el presentador de Noticias Telemundo, Julio Vaqueiro, en El Vaticano. El evento conmemora el d\u00e9cimo aniversario del papado de Francisco y Scholas Occurrentes, una organizaci\u00f3n desarrollada por el pont\u00edfice para apoyar a las comunidades pobres y marginadas de todo el mundo a trav\u00e9s de la educaci\u00f3n. M\u00e1s informaci\u00f3n de Scholas Occurrentes en: https:\/\/scholasoccurrentes.org\/ 00:00 - Recap 00:01 - Encuentro del papa con estudiantes del mundo 28:58 - Scholas ocurrentes cumple 10 a\u00f1os 32:28 - \u00bfScholas, una respuesta educativa a la crisis? 34:59 - Scholas y la crisis del medioambiente 38:04 - El rol de Scholas en la crisis del medioambiente 40:20 - Scholas y la crisis cultural 42:08 - Scholas y la falta de educaci\u00f3n integral 44:47 - Scholas y la crisis encuentro 47:11 - \u00bfC\u00f3mo combatir la crisis del desencuentro? 51:10 - Scholas y la crisis del sentido 52:56 - Sue\u00f1os e historias compartidos por j\u00f3venes 54:10 - Las conversaciones del papa cuando era ni\u00f1o 59:31 - Bendici\u00f3n de nueva sede de Scholas en Granada 1:00:19 - El papa recibe una camiseta en Napoli 1:06:49 - Preguntas al papa Descarga nuestra App: https:\/\/telemundo.app.link\/Mtq7sTKAUtb SUSCR\u00cdBETE: https:\/\/bit.ly\/TelemundoYTChannel Telemundo Es una empresa de medios de primera categor\u00eda, l\u00edder en la industria en la producci\u00f3n y distribuci\u00f3n de contenido en espa\u00f1ol de alta calidad a trav\u00e9s de m\u00faltiples plataformas para hispanos en los Estados Unidos y alrededor del mundo. La cadena ofrece producciones dram\u00e1ticas originales de Telemundo Studios \u2013 el productor #1 de contenido en espa\u00f1ol de horario estelar \u2013 as\u00ed como contenido alternativo, pel\u00edculas de cine, especiales, noticias y eventos deportivos de primer nivel, alcanzando el 94% de los televidentes hispanos en los Estados Unidos en 210 mercados a trav\u00e9s de 17 estaciones propias y 57 afiliadas de TV abierta. Telemundo tambi\u00e9n es propietaria de WKAQ, una estaci\u00f3n de televisi\u00f3n local que sirve Puerto Rico. Telemundo es parte de NBCUniversal Telemundo Enterprises, una divisi\u00f3n de NBCUniversal, una de las compa\u00f1\u00edas l\u00edderes en el mundo de los medios y entretenimiento. NBCUniversal es una subsidiaria de Comcast Corporation. Telemundo \u00a1Telemundo Now es tu destino digital para disfrutar la programaci\u00f3n que te gusta! Mira episodios completos de tus shows favoritos de Telemundo, al descargar la app Telemundo Now y entrar con tu cuenta de proveedor de TV. S\u00cdGUENOS EN TWITTER: http:\/\/bit.ly\/1vl4zqp DANOS ME GUSTA EN FACEBOOK: http:\/\/on.fb.me\/1EWlDol #Telemundo #Jovenes #PapaFrancisco El papa Francisco se re\u00fane con j\u00f3venes latinos de Scholas | Telemundo https:\/\/www.youtube.com\/telemundo\"><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/FTz5plfT9FM\/0.jpg\"><meta itemprop=\"duration\" content=\"PT1H34M41S\"><meta itemprop=\"uploadDate\" content=\"2023-05-25T15:41:58Z\"><\/span>\n<\/div><\/figure>\r\n","protected":false},"excerpt":{"rendered":"<p>Granada, Espagne. Jeudi dernier, le 25 mai 2023, la r\u00e9sidence Claret Granada a \u00e9t\u00e9 le th\u00e9\u00e2tre d&rsquo;un \u00e9v\u00e9nement capital : les r\u00e9sidents ont eu la rare opportunit\u00e9 de s&rsquo;entretenir en direct avec Sa Saintet\u00e9 le pape Fran\u00e7ois dans le cadre du projet \u00ab\u00a0Being Together\u00a0\u00bb (\u00catre ensemble). L&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 organis\u00e9 principalement par la Fondation Scholas, [&hellip;]<\/p>\n","protected":false},"author":69,"featured_media":147884,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[313],"tags":[],"class_list":["post-147900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatima-fr"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2023\/05\/charla-papa-francisco-RC-GRANADA_1.jpeg?fit=1600%2C900&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdaBmi-Ctu","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.claret.org\/fr\/wp-json\/wp\/v2\/posts\/147900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claret.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.claret.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.claret.org\/fr\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claret.org\/fr\/wp-json\/wp\/v2\/comments?post=147900"}],"version-history":[{"count":0,"href":"https:\/\/www.claret.org\/fr\/wp-json\/wp\/v2\/posts\/147900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.claret.org\/fr\/wp-json\/wp\/v2\/media\/147884"}],"wp:attachment":[{"href":"https:\/\/www.claret.org\/fr\/wp-json\/wp\/v2\/media?parent=147900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.claret.org\/fr\/wp-json\/wp\/v2\/categories?post=147900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.claret.org\/fr\/wp-json\/wp\/v2\/tags?post=147900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}