{"id":33574,"date":"2018-11-06T00:01:39","date_gmt":"2018-11-05T22:01:39","guid":{"rendered":"https:\/\/www.claret.org\/?p=33574"},"modified":"2018-11-06T00:53:33","modified_gmt":"2018-11-05T22:53:33","slug":"preghiera-per-la-beatificazione-di-padre-mariano-avellana-cmf","status":"publish","type":"post","link":"https:\/\/www.claret.org\/it\/preghiera-per-la-beatificazione-di-padre-mariano-avellana-cmf\/","title":{"rendered":"Preghiera per la beatificazione di Padre Mariano Avellana, CMF"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\">Dio, Padre onnipotente,<br \/>\nSignore del cielo e della terra,<br \/>\nradice della nostra vita<br \/>\ne del nostro impegno apostolico e missionario,<br \/>\nti preghiamo:<br \/>\ndona al nostro lstituto<br \/>\ne a quanti sono ad esso legati<br \/>\nla Beatificazione del Missionario Padre Mariano Avellana<br \/>\nla cui vita fu tanto nobilmente spesa<br \/>\nal servizio del Vangelo.<br \/>\nPer sua intercessione,<br \/>\nti chiediamo di accompagnare ii nostro cammino di fede<br \/>\ne di sostenerci nelle nostre umane infermita donandoci,<br \/>\nse e tuo volere, questa grazia<br \/>\nper la quale umilmente ti preghiamo<br \/>\nal fine di vivere ancora, e coerentemente,<br \/>\nla missione che ci hai affidato.<br \/>\nPer Cristo nostro Signore. Amen.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-33566\" src=\"https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2018\/11\/Ven-Padre-Mariano-Avellana.jpg?resize=1080%2C1543&#038;ssl=1\" alt=\"\" width=\"1080\" height=\"1543\" title=\"\" srcset=\"https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2018\/11\/Ven-Padre-Mariano-Avellana.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2018\/11\/Ven-Padre-Mariano-Avellana.jpg?resize=210%2C300&amp;ssl=1 210w, https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2018\/11\/Ven-Padre-Mariano-Avellana.jpg?resize=768%2C1097&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2018\/11\/Ven-Padre-Mariano-Avellana.jpg?resize=717%2C1024&amp;ssl=1 717w, https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2018\/11\/Ven-Padre-Mariano-Avellana.jpg?resize=1080%2C1543&amp;ssl=1 1080w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dio, Padre onnipotente, Signore del cielo e della terra, radice della nostra vita e del nostro impegno apostolico e missionario, ti preghiamo: dona al nostro lstituto e a quanti sono ad esso legati la Beatificazione del Missionario Padre Mariano Avellana la cui vita fu tanto nobilmente spesa al servizio del Vangelo. Per sua intercessione, ti [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33569,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[466,1882],"tags":[],"class_list":["post-33574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cause-dei-santi","category-mariano-avellana-it"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.claret.org\/wp-content\/uploads\/2018\/11\/Ven-Padre-Mariano-Avellana.jpg?fit=4134%2C5906&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdaBmi-8Jw","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.claret.org\/it\/wp-json\/wp\/v2\/posts\/33574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claret.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.claret.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.claret.org\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claret.org\/it\/wp-json\/wp\/v2\/comments?post=33574"}],"version-history":[{"count":0,"href":"https:\/\/www.claret.org\/it\/wp-json\/wp\/v2\/posts\/33574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.claret.org\/it\/wp-json\/wp\/v2\/media\/33569"}],"wp:attachment":[{"href":"https:\/\/www.claret.org\/it\/wp-json\/wp\/v2\/media?parent=33574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.claret.org\/it\/wp-json\/wp\/v2\/categories?post=33574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.claret.org\/it\/wp-json\/wp\/v2\/tags?post=33574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}